{"id":2284,"date":"2021-12-21T10:40:47","date_gmt":"2021-12-21T07:10:47","guid":{"rendered":"https:\/\/drvisite.ir\/mag\/?p=2284"},"modified":"2021-12-21T12:07:52","modified_gmt":"2021-12-21T08:37:52","slug":"measles","status":"publish","type":"post","link":"https:\/\/drvisite.com\/mag\/measles\/","title":{"rendered":"\u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9 \u0686\u06cc\u0633\u062a\u060c \u0686\u0647 \u0639\u0644\u0627\u0626\u0645 \u0648 \u0639\u0648\u0627\u0631\u0636\u06cc \u062f\u0627\u0631\u062f \u0648 \u0686\u06af\u0648\u0646\u0647 \u062f\u0631\u0645\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f\u061f"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0628\u0627 \u0627\u06cc\u0646 \u0645\u0648\u0627\u0631\u062f \u0622\u0634\u0646\u0627 \u0645\u06cc \u0634\u0648\u06cc\u062f<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/drvisite.com\/mag\/measles\/#%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D8%B3%D8%B1%D8%AE%DA%A9_%DA%86%DB%8C%D8%B3%D8%AA\" >\u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9 \u0686\u06cc\u0633\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/drvisite.com\/mag\/measles\/#%D8%B9%D9%84%D8%A7%D8%A6%D9%85_%D9%88_%D9%86%D8%B4%D8%A7%D9%86%D9%87_%D9%87%D8%A7%DB%8C_%D9%85%D9%87%D9%85_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D8%B3%D8%B1%D8%AE%DA%A9\" >\u0639\u0644\u0627\u0626\u0645 \u0648 \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u06cc \u0645\u0647\u0645 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/drvisite.com\/mag\/measles\/#%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D8%B3%D8%B1%D8%AE%DA%A9_%DA%86%D9%87_%D8%B2%D9%85%D8%A7%D9%86%DB%8C_%D8%A8%D8%A7%DB%8C%D8%AF_%D8%A8%D9%87_%D9%BE%D8%B2%D8%B4%DA%A9_%D9%85%D8%B1%D8%A7%D8%AC%D8%B9%D9%87_%DA%A9%D9%86%DB%8C%D9%85\" >\u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9 \u0686\u0647 \u0632\u0645\u0627\u0646\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u0645<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/drvisite.com\/mag\/measles\/#%D8%AF%D9%84%D8%A7%DB%8C%D9%84_%D8%A7%D8%A8%D8%AA%D9%84%D8%A7_%D8%A8%D9%87_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D8%B3%D8%B1%D8%AE%DA%A9\" >\u062f\u0644\u0627\u06cc\u0644 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/drvisite.com\/mag\/measles\/#%DA%86%D9%87_%D8%A7%D9%81%D8%B1%D8%A7%D8%AF%DB%8C_%D8%A8%DB%8C%D8%B4%D8%AA%D8%B1_%D8%AF%D8%B1_%D9%85%D8%B9%D8%B1%D8%B6_%D8%B3%D8%B1%D8%AE%DA%A9_%D9%87%D8%B3%D8%AA%D9%86%D8%AF\" >\u0686\u0647 \u0627\u0641\u0631\u0627\u062f\u06cc \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631 \u0645\u0639\u0631\u0636 \u0633\u0631\u062e\u06a9 \u0647\u0633\u062a\u0646\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/drvisite.com\/mag\/measles\/#%D8%B3%D8%B1%D8%AE%DA%A9_%DA%86%D9%87_%D8%B9%D9%88%D8%A7%D8%B1%D8%B6%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1_%D8%AF%D8%A7%D8%B1%D8%AF\" >\u0633\u0631\u062e\u06a9 \u0686\u0647 \u0639\u0648\u0627\u0631\u0636\u06cc \u0628\u0631\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631 \u062f\u0627\u0631\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/drvisite.com\/mag\/measles\/#%D8%B1%D8%A7%D9%87_%D9%87%D8%A7%DB%8C_%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%A7%D8%A8%D8%AA%D9%84%D8%A7_%D8%A8%D9%87_%D8%B3%D8%B1%D8%AE%DA%A9_%D8%B1%D8%A7_%D8%A8%D8%B4%D9%86%D8%A7%D8%B3%DB%8C%D8%AF\" >\u0631\u0627\u0647 \u0647\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0633\u0631\u062e\u06a9 \u0631\u0627 \u0628\u0634\u0646\u0627\u0633\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/drvisite.com\/mag\/measles\/#%D8%B1%D8%A7%D9%87_%D9%87%D8%A7%DB%8C_%D8%AA%D8%B4%D8%AE%DB%8C%D8%B5_%D9%88_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D8%B3%D8%B1%D8%AE%DA%A9\" >\u0631\u0627\u0647 \u0647\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/drvisite.com\/mag\/measles\/#%DA%A9%D9%84%D8%A7%D9%85_%D8%A2%D8%AE%D8%B1\" >\u06a9\u0644\u0627\u0645 \u0622\u062e\u0631<\/a><\/li><\/ul><\/nav><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #1d4076;\"><strong>\u067e\u0648\u0633\u062a \u0627\u0646\u0633\u0627\u0646 \u06cc\u06a9 \u0639\u0636\u0648 \u0628\u0633\u06cc\u0627\u0631 \u062d\u0633\u0627\u0633 \u0648 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631 \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0645\u0631\u0627\u0642\u0628\u062a \u0632\u06cc\u0627\u062f \u062f\u0627\u0631\u062f. \u062e\u0634\u06a9\u06cc\u060c \u0627\u0644\u062a\u0647\u0627\u0628\u060c \u0633\u0631\u062e\u06a9\u060c <a href=\"https:\/\/drvisite.ir\/mag\/chicken-pox\/\" target=\"_blank\" rel=\"noopener\">\u0622\u0628\u0644\u0647<\/a> \u0648&#8230; \u0627\u0632 \u062c\u0645\u0644\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u067e\u0648\u0633\u062a \u0631\u0627 \u062a\u0647\u062f\u06cc\u062f \u0645\u06cc \u06a9\u0646\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u062d\u0633\u0627\u0633\u06cc\u062a \u0628\u0627\u0644\u0627\u06cc \u0627\u06cc\u0646 \u0639\u0636\u0648 \u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627\u060c \u0631\u0627\u0647 \u0647\u0627\u06cc \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0648 \u062f\u0631\u0645\u0627\u0646 \u0622\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0627\u0632 \u067e\u0648\u0633\u062a \u062f\u0631\u0628\u0631\u0627\u0628\u0631 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627 \u0645\u062d\u0627\u0641\u0638\u062a \u06a9\u0631\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u0645 \u0636\u0645\u0646 \u0628\u0631\u0631\u0633\u06cc \u0633\u0631\u062e\u06a9 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc \u0639\u0644\u0627\u0626\u0645\u060c \u0639\u0644\u0644\u060c \u0631\u0627\u0647 \u0647\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0622\u0646 \u0631\u0627 \u0645\u0639\u0631\u0641\u06cc \u06a9\u0646\u06cc\u0645.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D8%B3%D8%B1%D8%AE%DA%A9_%DA%86%DB%8C%D8%B3%D8%AA\"><\/span><span style=\"color: #1895a7;\">\u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9 \u0686\u06cc\u0633\u062a<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\">\u0633\u0631\u062e\u06a9 \u06cc\u06a9 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0639\u0641\u0648\u0646\u06cc \u0648 \u062a\u0646\u0641\u0633\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0642\u062f\u0631\u062a \u0633\u0631\u0627\u06cc\u062a \u0648 \u0627\u0646\u062a\u0642\u0627\u0644 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f. \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06a9\u0647 \u0645\u0639\u0645\u0648\u0644\u0627 \u062f\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0638\u0627\u0647\u0631 \u0645\u06cc \u0634\u0648\u062f \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0634\u0646\u062f\u0647 \u0648 \u062e\u0637\u0631\u0646\u0627\u06a9 \u0628\u0627\u0634\u062f. \u0628\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0627\u0645\u0631\u0648\u0632\u0647 \u062a\u0627 \u062d\u062f\u0648\u062f\u06cc \u0642\u0627\u0628\u0644 \u06a9\u0646\u062a\u0631\u0644 \u0648 \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u062f\u0631 \u0639\u06cc\u0646 \u062d\u0627\u0644 \u062f\u0631 \u062c\u0647\u0627\u0646 \u0633\u0627\u0644\u0627\u0646\u0647 \u062d\u062f\u0648\u062f 100000 \u0647\u0632\u0627\u0631 \u0645\u0631\u06af \u0628\u0631 \u0627\u062b\u0631 \u0633\u0631\u062e\u06a9 \u062b\u0628\u062a \u0645\u06cc \u0634\u0648\u062f \u06a9\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0622\u0646\u0647\u0627 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0632\u06cc\u0631 5 \u0633\u0627\u0644 \u0645\u06cc \u0628\u0627\u0634\u062f.<\/span><\/h3>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B9%D9%84%D8%A7%D8%A6%D9%85_%D9%88_%D9%86%D8%B4%D8%A7%D9%86%D9%87_%D9%87%D8%A7%DB%8C_%D9%85%D9%87%D9%85_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D8%B3%D8%B1%D8%AE%DA%A9\"><\/span><span style=\"color: #1895a7;\">\u0639\u0644\u0627\u0626\u0645 \u0648 \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u06cc \u0645\u0647\u0645 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\">\u0639\u0644\u0627\u0626\u0645 \u0633\u0631\u062e\u06a9 \u0645\u0639\u0645\u0648\u0644\u0627 \u0628\u06cc\u0646 10 \u0627\u0644\u06cc 14 \u0631\u0648\u0632 \u067e\u0633 \u0627\u0632 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646 \u062f\u0631 \u0645\u0639\u0631\u0636 \u0648\u06cc\u0631\u0648\u0633 \u0638\u0627\u0647\u0631 \u0645\u06cc \u0634\u0648\u0646\u062f. \u0627\u06cc\u0646 \u0639\u0644\u0627\u0626\u0645 \u0639\u0628\u0627\u0631\u062a \u0627\u0646\u062f \u0627\u0632:<\/span><\/h3>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"color: #1d4076;\"><strong>\u062a\u0628<\/strong><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #1d4076;\"><strong>\u0633\u0631\u0641\u0647 \u062e\u0634\u06a9<\/strong><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #1d4076;\"><strong>\u0622\u0628\u0631\u06cc\u0632\u0634 \u0628\u06cc\u0646\u06cc<\/strong><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #1d4076;\"><strong>\u06af\u0644\u0648\u062f\u0631\u062f<\/strong><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #1d4076;\"><strong>\u0627\u0644\u062a\u0647\u0627\u0628 \u0645\u0644\u062a\u062d\u0645\u0647<\/strong><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #1d4076;\"><strong>\u0633\u0631\u062e\u06cc \u067e\u0648\u0633\u062a \u0648 \u0627\u06cc\u062c\u0627\u062f \u062c\u0648\u0634 \u0647\u0627\u06cc \u0633\u0641\u06cc\u062f \u0631\u0648 \u0622\u0646<\/strong><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #1d4076;\"><strong>\u0627\u06cc\u062c\u0627\u062f \u0644\u06a9\u0647 \u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u0648 \u0628\u0631\u062c\u0633\u062a\u0647 \u0631\u0648\u06cc \u067e\u0648\u0633\u062a<\/strong><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D8%B3%D8%B1%D8%AE%DA%A9_%DA%86%D9%87_%D8%B2%D9%85%D8%A7%D9%86%DB%8C_%D8%A8%D8%A7%DB%8C%D8%AF_%D8%A8%D9%87_%D9%BE%D8%B2%D8%B4%DA%A9_%D9%85%D8%B1%D8%A7%D8%AC%D8%B9%D9%87_%DA%A9%D9%86%DB%8C%D9%85\"><\/span><span style=\"color: #1895a7;\">\u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9 \u0686\u0647 \u0632\u0645\u0627\u0646\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u0645<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\">\u0633\u0631\u062e\u06a9 \u0627\u0628\u062a\u062f\u0627 \u0628\u0627 \u0639\u0644\u0627\u0626\u0645 \u062e\u0641\u06cc\u0641\u060c \u0645\u062b\u0644 \u062a\u0628 \u062e\u0641\u06cc\u0641 \u0634\u0631\u0648\u0639 \u0645\u06cc \u0634\u0648\u062f. \u0628\u0627 \u0645\u0631\u0648\u0631 \u0632\u0645\u0627\u0646 \u0627\u06cc\u0646 \u0639\u0644\u0627\u0626\u0645 \u0634\u062f\u06cc\u062f \u062a\u0631 \u0634\u062f\u0647 \u0648 \u0628\u062f\u0646 \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u062f\u0631\u06af\u06cc\u0631 \u0645\u06cc \u06a9\u0646\u062f. \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0647\u0627 \u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u0628\u0627 \u0645\u0634\u0627\u0647\u062f\u0647 \u0627\u0648\u0644\u06cc\u0646 \u0639\u0644\u0627\u0645\u062a \u0633\u0631\u062e\u06a9\u060c \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u062a\u062e\u0635\u0635 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u0646\u062f.<\/span><\/h3>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AF%D9%84%D8%A7%DB%8C%D9%84_%D8%A7%D8%A8%D8%AA%D9%84%D8%A7_%D8%A8%D9%87_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D8%B3%D8%B1%D8%AE%DA%A9\"><\/span><span style=\"color: #1895a7;\">\u062f\u0644\u0627\u06cc\u0644 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\">\u0633\u0631\u062e\u06a9 \u06cc\u06a9 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0645\u0633\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062a\u0648\u0633\u0637 \u0648\u06cc\u0631\u0648\u0633 \u0647\u0627\u06cc \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0628\u06cc\u0646\u06cc \u06cc\u0627 \u06af\u0644\u0648\u06cc \u0628\u06cc\u0645\u0627\u0631 \u0627\u0633\u062a \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc \u0634\u0648\u062f.\u0628\u06cc\u0645\u0627\u0631 \u062f\u0631 \u0635\u0648\u0631\u062a \u0639\u0637\u0633\u0647 \u06cc\u0627 \u0633\u0631\u0641\u0647 \u0630\u0631\u0627\u062a \u0648\u06cc\u0631\u0648\u0633 \u0631\u0627 \u062f\u0631 \u0647\u0648\u0627 \u0622\u0632\u0627\u062f \u06a9\u0631\u062f\u0647 \u0648 \u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u0645\u0639\u0631\u0636 \u0631\u0627 \u0628\u0647 \u0633\u0631\u0639\u062a \u0645\u0628\u062a\u0644\u0627 \u0645\u06cc \u06a9\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0645\u0627\u0646\u062f\u06af\u0627\u0631\u06cc \u0628\u0627\u0644\u0627\u06cc\u06cc \u0628\u0631 \u0631\u0648\u06cc \u0633\u0637\u0648\u062d \u062f\u0627\u0631\u062f \u0648 \u0628\u0647 \u0645\u062d\u0636 \u062a\u0645\u0627\u0633 \u062f\u0633\u062a \u0622\u0644\u0648\u062f\u0647 \u0628\u0627 \u0635\u0648\u0631\u062a\u060c \u0645\u0646\u062a\u0642\u0644 \u0645\u06cc \u0634\u0648\u062f. \u0633\u0631\u0627\u06cc\u062a \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0628\u0647 \u062d\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 90% \u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u0645\u0639\u0631\u0636 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0631\u0627 \u062f\u0631\u06af\u06cc\u0631 \u0645\u06cc \u06a9\u0646\u062f.<\/span><\/h3>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%86%D9%87_%D8%A7%D9%81%D8%B1%D8%A7%D8%AF%DB%8C_%D8%A8%DB%8C%D8%B4%D8%AA%D8%B1_%D8%AF%D8%B1_%D9%85%D8%B9%D8%B1%D8%B6_%D8%B3%D8%B1%D8%AE%DA%A9_%D9%87%D8%B3%D8%AA%D9%86%D8%AF\"><\/span><span style=\"color: #1895a7;\">\u0686\u0647 \u0627\u0641\u0631\u0627\u062f\u06cc \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631 \u0645\u0639\u0631\u0636 \u0633\u0631\u062e\u06a9 \u0647\u0633\u062a\u0646\u062f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li style=\"text-align: justify;\">\n<h3><span style=\"font-size: 16px; color: #1d4076;\">\u0633\u0631\u062e\u06a9 \u0627\u0641\u0631\u0627\u062f\u06cc \u0631\u0627 \u06a9\u0647 \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0648\u0627\u06a9\u0633\u06cc\u0646\u0647 \u0646\u0634\u062f\u0647 \u0627\u0646\u062f \u0631\u0627 \u0628\u06cc\u0634\u062a\u0631 \u062a\u0647\u062f\u06cc\u062f \u0645\u06cc \u06a9\u0646\u062f.<\/span><\/h3>\n<\/li>\n<li style=\"text-align: justify;\">\n<h3><span style=\"font-size: 16px; color: #1d4076;\">\u06a9\u0645\u0628\u0648\u062f \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 A \u062f\u0631 \u0628\u062f\u0646 \u0646\u06cc\u0632 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0634\u0627\u0646\u0633 \u0627\u0628\u062a\u0644\u0627 \u0631\u0627 \u0628\u0627\u0644\u0627 \u0628\u0628\u0631\u062f.<\/span><\/h3>\n<\/li>\n<li style=\"text-align: justify;\">\n<h3><span style=\"font-size: 16px; color: #1d4076;\">\u0633\u0641\u0631 \u0628\u0647 \u062e\u0627\u0631\u062c \u0627\u0632 \u06a9\u0634\u0648\u0631 \u0646\u06cc\u0632 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u062e\u0637\u0631 \u0627\u0628\u062a\u0644\u0627 \u062f\u0631 \u0641\u0631\u062f \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u062f.<\/span><\/h3>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B3%D8%B1%D8%AE%DA%A9_%DA%86%D9%87_%D8%B9%D9%88%D8%A7%D8%B1%D8%B6%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1_%D8%AF%D8%A7%D8%B1%D8%AF\"><\/span><span style=\"color: #1895a7;\">\u0633\u0631\u062e\u06a9 \u0686\u0647 \u0639\u0648\u0627\u0631\u0636\u06cc \u0628\u0631\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631 \u062f\u0627\u0631\u062f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\">\u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0639\u0648\u0627\u0631\u0636 \u0632\u06cc\u0631 \u0631\u0627 \u062f\u0631 \u067e\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/span><\/h3>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\"><span style=\"color: #1895a7;\">\u0639\u0641\u0648\u0646\u062a \u06af\u0648\u0634 :<\/span> \u0639\u0641\u0648\u0646\u062a \u0628\u0627\u06a9\u062a\u0631\u06cc\u0627\u06cc\u06cc \u06af\u0648\u0634 \u0627\u0632 \u0639\u0648\u0627\u0631\u0636 \u0634\u0627\u06cc\u0639 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f.<\/span><\/h3>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\"><span style=\"color: #1895a7;\">\u0628\u0631\u0648\u0646\u0634\u06cc\u062a\u060c \u0644\u0627\u0631\u0646\u0698\u06cc\u062a \u06cc\u0627 \u06a9\u0631\u0648\u067e :<\/span> \u0633\u0631\u062e\u06a9 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u0644\u062a\u0647\u0627\u0628 \u062d\u0646\u062c\u0631\u0647 \u0648 \u06cc\u0627 \u0627\u0644\u062a\u0647\u0627\u0628 \u062f\u06cc\u0648\u0627\u0631\u0647 \u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u067e\u0648\u0634\u0627\u0646\u0646\u062f\u0647 \u0631\u06cc\u0647 \u0634\u0648\u062f.<\/span><\/h3>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\"><span style=\"color: #1895a7;\">\u067e\u0646\u0648\u0645\u0648\u0646\u06cc (\u0630\u0627\u062a \u0627\u0644\u0631\u06cc\u0647) :<\/span> \u062f\u0631 \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0636\u0639\u06cc\u0641\u06cc \u062f\u0627\u0631\u0646\u062f \u0630\u0627\u062a \u0627\u0644\u0631\u06cc\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0639\u0648\u0627\u0631\u0636 \u0634\u0627\u06cc\u0639 \u0633\u0631\u062e\u06a9 \u0645\u06cc \u0628\u0627\u0634\u062f.<\/span><\/h3>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\"><span style=\"color: #1895a7;\">\u0627\u0644\u062a\u0647\u0627\u0628 \u0645\u063a\u0632 :<\/span> \u0627\u0632 \u0628\u06cc\u0646 1000 \u0628\u06cc\u0645\u0627\u0631 \u0645\u0628\u062a\u0644\u0627 \u0628\u0647 \u0633\u0631\u062e\u06a9 1 \u0646\u0641\u0631 \u0628\u0647 \u0627\u0644\u062a\u0647\u0627\u0628 \u0645\u063a\u0632 \u0645\u0628\u062a\u0644\u0627 \u0645\u06cc \u0634\u0648\u062f. \u0627\u06cc\u0646 \u0639\u0627\u0631\u0636\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0633\u0631\u062e\u06a9 \u06cc\u0627 \u0645\u0627\u0647 \u0647\u0627 \u0628\u0639\u062f \u0627\u0632 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0633\u0631\u062e\u06a9 \u0627\u06cc\u062c\u0627\u062f \u0634\u0648\u062f.<\/span><\/h3>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\"><span style=\"color: #1895a7;\">\u0645\u0634\u06a9\u0644\u0627\u062a \u0628\u0627\u0631\u062f\u0631\u0627\u06cc :<\/span> \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0633\u0631\u062e\u06a9 \u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0639\u062b \u0632\u0627\u06cc\u0645\u0627\u0646 \u0632\u0648\u062f\u0631\u0633\u060c \u0648\u0632\u0646 \u06a9\u0645 \u0646\u0648\u0632\u0627\u062f \u0648 \u06cc\u0627 \u0645\u0631\u06af \u0645\u0627\u062f\u0631 \u0634\u0648\u062f.<\/span><\/h3>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B1%D8%A7%D9%87_%D9%87%D8%A7%DB%8C_%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%A7%D8%A8%D8%AA%D9%84%D8%A7_%D8%A8%D9%87_%D8%B3%D8%B1%D8%AE%DA%A9_%D8%B1%D8%A7_%D8%A8%D8%B4%D9%86%D8%A7%D8%B3%DB%8C%D8%AF\"><\/span><span style=\"color: #1895a7;\">\u0631\u0627\u0647 \u0647\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0633\u0631\u062e\u06a9 \u0631\u0627 \u0628\u0634\u0646\u0627\u0633\u06cc\u062f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\"><span style=\"color: #1895a7;\">\u0648\u0627\u06a9\u0633\u0646 :<\/span> \u0628\u0647\u062a\u0631\u06cc\u0646 \u0648 \u0627\u06cc\u0645\u0646 \u062a\u0631\u06cc\u0646 \u0631\u0627\u0647 \u0628\u0631\u0627\u06cc \u062f\u0631 \u0627\u0645\u0627\u0646 \u0645\u0627\u0646\u062f\u0646 \u0627\u0632 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062a\u0632\u0631\u06cc\u0642 2 \u062f\u0648\u0632 \u0648\u0627\u06a9\u0633\u0646 \u0633\u0631\u062e\u06a9 \u0645\u06cc \u0628\u0627\u0634\u062f. \u0627\u06cc\u0646 \u0648\u0627\u06a9\u0633\u0646 \u062f\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062f\u0631 \u062f\u0648 \u0645\u0631\u062d\u0644\u0647 \u06a9\u0647 \u0645\u0631\u062d\u0644\u0647 \u0627\u0648\u0644 \u0622\u0646 \u0628\u06cc\u0646 12 \u062a\u0627 15 \u0645\u0627\u0647\u06af\u06cc \u0648 \u0645\u0631\u062d\u0644\u0647 \u062f\u0648\u0645 \u0628\u06cc\u0646 4 \u062a\u0627 6 \u0633\u0627\u0644\u06af\u06cc \u062a\u0632\u0631\u06cc\u0642 \u0645\u06cc \u0634\u0648\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06cc\u0646 \u0648\u0627\u06a9\u0633\u0646 \u062f\u0631 \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u0627\u0646 \u0647\u0645 \u062f\u0631 \u0635\u0648\u0631\u062a \u0639\u062f\u0645 \u062a\u0632\u0631\u06cc\u0642 \u062f\u0631 \u06a9\u0648\u062f\u06a9\u06cc \u0628\u0627 \u062a\u0634\u062e\u06cc\u0635 \u067e\u0632\u0634\u06a9 \u062a\u0632\u0631\u06cc\u0642 \u0645\u06cc \u0634\u0648\u062f.<\/span><\/h3>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\"><span style=\"color: #1895a7;\">\u0642\u0631\u0646\u0637\u06cc\u0646\u0647 :<\/span> \u062f\u0631 \u0645\u0648\u0627\u062c\u0647 \u0628\u0627 \u0641\u0631\u062f \u0645\u0628\u062a\u0644\u0627 \u0642\u0631\u0646\u0637\u06cc\u0647 \u06a9\u0631\u062f\u0646 \u0628\u06cc\u0645\u0627\u0631 \u0648 \u0631\u0639\u0627\u06cc\u062a \u0641\u0627\u0635\u0644\u0647 \u0644\u0627\u0632\u0645 \u0627\u0632 \u0645\u0647\u0645\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647 \u0647\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f.<\/span><\/h3>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B1%D8%A7%D9%87_%D9%87%D8%A7%DB%8C_%D8%AA%D8%B4%D8%AE%DB%8C%D8%B5_%D9%88_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D8%B3%D8%B1%D8%AE%DA%A9\"><\/span><span style=\"color: #1895a7;\">\u0631\u0627\u0647 \u0647\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\">\u067e\u0632\u0634\u06a9 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0639\u0644\u0627\u0626\u0645 \u0638\u0627\u0647\u0631\u06cc \u0648 \u0644\u06a9\u0647 \u0647\u0627\u06cc \u0645\u0648\u062c\u0648\u062f \u0631\u0648\u06cc \u067e\u0648\u0633\u062a \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0646\u0645\u0648\u0646\u0647 \u0628\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 \u0628\u0632\u0627\u0642 \u0648 \u0627\u062f\u0631\u0627\u0631\u060c \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0631\u0627 \u062a\u0634\u062e\u06cc\u0635 \u0645\u06cc \u062f\u0647\u062f. \u062f\u0631\u0645\u0627\u0646 \u0645\u0634\u062e\u0635\u06cc \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f \u0648 \u067e\u0632\u0634\u06a9\u0627\u0646 \u0627\u0632 \u062f\u0631\u0645\u0627\u0646 \u0647\u0627\u06cc \u0645\u06a9\u0645\u0644 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u0639\u0648\u0627\u0631\u0636 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u0646\u062f. \u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u062f\u0627\u0631\u0648\u06cc\u06cc\u060c \u067e\u0632\u0634\u06a9 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u062a\u0628 \u0628\u0631\u060c \u0627\u0646\u0648\u0627\u0639 \u0622\u0646\u062a\u06cc \u0628\u06cc\u0648\u062a\u06cc\u06a9 \u0647\u0627 \u0648 \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 A \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631 \u062a\u062c\u0648\u06cc\u0632 \u06a9\u0646\u062f.<\/span><\/h3>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D9%84%D8%A7%D9%85_%D8%A2%D8%AE%D8%B1\"><\/span><span style=\"color: #1895a7;\">\u06a9\u0644\u0627\u0645 \u0622\u062e\u0631<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; color: #1d4076;\"><span style=\"color: #1895a7;\"><a style=\"color: #1895a7;\" href=\"https:\/\/drvisite.ir\/mag\/category\/physical-health\/skin-and-hair\/\" target=\"_blank\" rel=\"noopener\">\u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc<\/a><\/span> \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0628\u062f\u0648\u0646 \u0645\u062d\u0627\u0641\u0637 \u0628\u0648\u062f\u0646 \u067e\u0648\u0633\u062a \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0639\u0648\u0627\u0645\u0644 \u062e\u0627\u0631\u062c\u06cc \u06cc\u06a9\u06cc \u0627\u0632 \u0634\u0627\u06cc\u0639 \u062a\u0631\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627 \u0645\u06cc \u0628\u0627\u0634\u062f. \u0633\u0631\u062e\u06a9 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc\u060c \u0639\u0644\u0627\u0626\u0645 \u0648 \u0639\u0648\u0627\u0631\u0636 \u0645\u0634\u062e\u0635\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u0634\u0646\u0627\u062e\u062a \u0622\u0646\u0647\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u06a9\u0645 \u06a9\u0631\u062f\u0646 \u0639\u0648\u0627\u0631\u0636 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0645\u0641\u06cc\u062f \u0648 \u0645\u0648\u062b\u0631 \u0628\u0627\u0634\u062f.<\/span><\/h3>\n<p><script type=\"application\/ld+json\">\n{\n  \"@context\": \"https:\/\/schema.org\",\n  \"@type\": \"FAQPage\",\n  \"mainEntity\": [{\n    \"@type\": \"Question\",\n    \"name\": \"\u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9 \u0686\u06cc\u0633\u062a\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"\u0633\u0631\u062e\u06a9 \u06cc\u06a9 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0639\u0641\u0648\u0646\u06cc \u0648 \u062a\u0646\u0641\u0633\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0642\u062f\u0631\u062a \u0633\u0631\u0627\u06cc\u062a \u0648 \u0627\u0646\u062a\u0642\u0627\u0644 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f. \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06a9\u0647 \u0645\u0639\u0645\u0648\u0644\u0627 \u062f\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0638\u0627\u0647\u0631 \u0645\u06cc \u0634\u0648\u062f \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0634\u0646\u062f\u0647 \u0648 \u062e\u0637\u0631\u0646\u0627\u06a9 \u0628\u0627\u0634\u062f. \u0628\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0627\u0645\u0631\u0648\u0632\u0647 \u062a\u0627 \u062d\u062f\u0648\u062f\u06cc \u0642\u0627\u0628\u0644 \u06a9\u0646\u062a\u0631\u0644 \u0648 \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u062f\u0631 \u0639\u06cc\u0646 \u062d\u0627\u0644 \u062f\u0631 \u062c\u0647\u0627\u0646 \u0633\u0627\u0644\u0627\u0646\u0647 \u062d\u062f\u0648\u062f 100000 \u0647\u0632\u0627\u0631 \u0645\u0631\u06af \u0628\u0631 \u0627\u062b\u0631 \u0633\u0631\u062e\u06a9 \u062b\u0628\u062a \u0645\u06cc \u0634\u0648\u062f \u06a9\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0622\u0646\u0647\u0627 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0632\u06cc\u0631 5 \u0633\u0627\u0644 \u0645\u06cc \u0628\u0627\u0634\u062f.\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"\u0639\u0644\u0627\u0626\u0645 \u0648 \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u06cc \u0645\u0647\u0645 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"\u062a\u0628\n\u0633\u0631\u0641\u0647 \u062e\u0634\u06a9\n\u0622\u0628\u0631\u06cc\u0632\u0634 \u0628\u06cc\u0646\u06cc\n\u06af\u0644\u0648\u062f\u0631\u062f\n\u0627\u0644\u062a\u0647\u0627\u0628 \u0645\u0644\u062a\u062d\u0645\u0647\n\u0633\u0631\u062e\u06cc \u067e\u0648\u0633\u062a \u0648 \u0627\u06cc\u062c\u0627\u062f \u062c\u0648\u0634 \u0647\u0627\u06cc \u0633\u0641\u06cc\u062f \u0631\u0648 \u0622\u0646\n\u0627\u06cc\u062c\u0627\u062f \u0644\u06a9\u0647 \u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u0648 \u0628\u0631\u062c\u0633\u062a\u0647 \u0631\u0648\u06cc \u067e\u0648\u0633\u062a\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"\u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u062e\u06a9 \u0686\u0647 \u0632\u0645\u0627\u0646\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u0645\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"\u0633\u0631\u062e\u06a9 \u0627\u0628\u062a\u062f\u0627 \u0628\u0627 \u0639\u0644\u0627\u0626\u0645 \u062e\u0641\u06cc\u0641\u060c \u0645\u062b\u0644 \u062a\u0628 \u062e\u0641\u06cc\u0641 \u0634\u0631\u0648\u0639 \u0645\u06cc \u0634\u0648\u062f. \u0628\u0627 \u0645\u0631\u0648\u0631 \u0632\u0645\u0627\u0646 \u0627\u06cc\u0646 \u0639\u0644\u0627\u0626\u0645 \u0634\u062f\u06cc\u062f \u062a\u0631 \u0634\u062f\u0647 \u0648 \u0628\u062f\u0646 \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u062f\u0631\u06af\u06cc\u0631 \u0645\u06cc \u06a9\u0646\u062f. \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0647\u0627 \u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u0628\u0627 \u0645\u0634\u0627\u0647\u062f\u0647 \u0627\u0648\u0644\u06cc\u0646 \u0639\u0644\u0627\u0645\u062a \u0633\u0631\u062e\u06a9\u060c \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u062a\u062e\u0635\u0635 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u0646\u062f.\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"\u0686\u0647 \u0627\u0641\u0631\u0627\u062f\u06cc \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631 \u0645\u0639\u0631\u0636 \u0633\u0631\u062e\u06a9 \u0647\u0633\u062a\u0646\u062f\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"\u0633\u0631\u062e\u06a9 \u0627\u0641\u0631\u0627\u062f\u06cc \u0631\u0627 \u06a9\u0647 \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0648\u0627\u06a9\u0633\u06cc\u0646\u0647 \u0646\u0634\u062f\u0647 \u0627\u0646\u062f \u0631\u0627 \u0628\u06cc\u0634\u062a\u0631 \u062a\u0647\u062f\u06cc\u062f \u0645\u06cc \u06a9\u0646\u062f.\n\u06a9\u0645\u0628\u0648\u062f \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 A \u062f\u0631 \u0628\u062f\u0646 \u0646\u06cc\u0632 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0634\u0627\u0646\u0633 \u0627\u0628\u062a\u0644\u0627 \u0631\u0627 \u0628\u0627\u0644\u0627 \u0628\u0628\u0631\u062f.\n\u0633\u0641\u0631 \u0628\u0647 \u062e\u0627\u0631\u062c \u0627\u0632 \u06a9\u0634\u0648\u0631 \u0646\u06cc\u0632 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u062e\u0637\u0631 \u0627\u0628\u062a\u0644\u0627 \u062f\u0631 \u0641\u0631\u062f \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u062f.\"\n    }\n  }]\n}\n<\/script><\/p>\n\r\n\t\t<div class=\"review_wrap\">\r\n\t\t\t<div id=\"review-box\" class=\"review-box review-bottom review-stars\">\r\n\t\t\t\t<div class=\"review-summary\">\r\n\t\t\t\t\t<div class=\"review-final-score\">\r\n\t\t\t\t\t\t<span title=\"\" class=\"post-large-rate stars-large\"><span style=\"width:0%\"><\/span><\/span>\r\n\t\t\t\t\t\t<h4><\/h4>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"review-short-summary\">\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t<div class=\"user-rate-wrap\">\r\n\t\t\t\t<span class=\"user-rating-text\">\r\n\t\t\t\t\t<strong>\u0627\u0645\u062a\u06cc\u0627\u0632 \u06a9\u0627\u0631\u0628\u0631: <\/strong>\r\n\t\t\t\t\t<span class=\"taq-score\"><\/span>\r\n\t\t\t\t\t<small>\u0627\u0648\u0644\u06cc\u0646 \u0646\u0641\u0631 \u0628\u0627\u0634\u06cc\u062f !<\/small>\r\n\t\t\t\t<\/span>\r\n\r\n\t\t\t\t<div data-rate=\"0\" data-id=\"2284\" class=\"user-rate taq-user-rate-active\">\r\n\t\t\t\t\t<span class=\"user-rate-image post-large-rate stars-large\">\r\n\t\t\t\t\t\t<span style=\"width:0%\"><\/span>\r\n\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"taq-clear\"><\/div>\r\n\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u067e\u0648\u0633\u062a \u0627\u0646\u0633\u0627\u0646 \u06cc\u06a9 \u0639\u0636\u0648 \u0628\u0633\u06cc\u0627\u0631 \u062d\u0633\u0627\u0633 \u0648 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631 \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0645\u0631\u0627\u0642\u0628\u062a \u0632\u06cc\u0627\u062f \u062f\u0627\u0631\u062f. \u062e\u0634\u06a9\u06cc\u060c \u0627\u0644\u062a\u0647\u0627\u0628\u060c \u0633\u0631\u062e\u06a9\u060c \u0622\u0628\u0644\u0647 \u0648&#8230; \u0627\u0632 \u062c\u0645\u0644\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u067e\u0648\u0633\u062a \u0631\u0627 \u062a\u0647\u062f\u06cc\u062f \u0645\u06cc \u06a9\u0646\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u062d\u0633\u0627\u0633\u06cc\u062a \u0628\u0627\u0644\u0627\u06cc \u0627\u06cc\u0646 \u0639\u0636\u0648 \u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627\u060c \u0631\u0627\u0647 \u0647\u0627\u06cc \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0648 \u062f\u0631\u0645\u0627\u0646 \u0622\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":2285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97,83],"tags":[],"class_list":["post-2284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-physical-health","category-skin-and-hair"],"_links":{"self":[{"href":"https:\/\/drvisite.com\/mag\/wp-json\/wp\/v2\/posts\/2284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drvisite.com\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drvisite.com\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drvisite.com\/mag\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/drvisite.com\/mag\/wp-json\/wp\/v2\/comments?post=2284"}],"version-history":[{"count":4,"href":"https:\/\/drvisite.com\/mag\/wp-json\/wp\/v2\/posts\/2284\/revisions"}],"predecessor-version":[{"id":2289,"href":"https:\/\/drvisite.com\/mag\/wp-json\/wp\/v2\/posts\/2284\/revisions\/2289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drvisite.com\/mag\/wp-json\/wp\/v2\/media\/2285"}],"wp:attachment":[{"href":"https:\/\/drvisite.com\/mag\/wp-json\/wp\/v2\/media?parent=2284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drvisite.com\/mag\/wp-json\/wp\/v2\/categories?post=2284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drvisite.com\/mag\/wp-json\/wp\/v2\/tags?post=2284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}